{"id":88998,"date":"2024-10-28T13:40:21","date_gmt":"2024-10-28T13:40:21","guid":{"rendered":"https:\/\/www.expondo.co.uk\/inspirations\/jardin-en-automne\/"},"modified":"2024-10-28T13:46:42","modified_gmt":"2024-10-28T13:46:42","slug":"jardin-en-automne","status":"publish","type":"post","link":"https:\/\/www.expondo.be\/inspirations\/jardin-en-automne\/","title":{"rendered":"Guide jardinage\u00a0: que planter dans le jardin en automne et comment\u00a0?"},"content":{"rendered":"\n<p><strong>L&#8217;automne marque la fin des beaux jours. C&#8217;est n\u00e9anmoins aussi la saison id\u00e9ale pour r\u00e9aliser certains travaux de jardinage essentiels. C&#8217;est le moment de planter des arbres, des arbustes ou encore des bulbes. Comment pr\u00e9parer son jardin en automne pour qu&#8217;il fleurisse, d\u00e9veloppe ses couleurs et que les arbres soient en pleine sant\u00e9 au printemps&nbsp;?<\/strong><\/p>\n\n\n<div class=\"wp-block-ub-table-of-contents-block ub_table-of-contents\" data-showtext=\"show\" data-hidetext=\"hide\" data-scrolltype=\"auto\" id=\"ub_table-of-contents-9659eb60-0def-458a-aaa3-9f586807b908\" data-initiallyhideonmobile=\"false\"\n                    data-initiallyshow=\"true\"><div class=\"ub_table-of-contents-header-container\"><div class=\"ub_table-of-contents-header\">\n                    <div class=\"ub_table-of-contents-title\"><\/div><\/div><\/div><div class=\"ub_table-of-contents-extra-container\"><div class=\"ub_table-of-contents-container ub_table-of-contents-1-column \"><ul><li><a href=https:\/\/www.expondo.be\/inspirations\/jardin-en-automne\/#0-comment-pr%C3%A9parer-mon-jardin-%C3%A0-lautomne->Comment pr\u00e9parer mon jardin \u00e0 l&#8217;automne&nbsp;?<\/a><\/li><li><a href=https:\/\/www.expondo.be\/inspirations\/jardin-en-automne\/#1-les-v%C3%A9g%C3%A9taux-%C3%A0-planter-en-automne>Les v\u00e9g\u00e9taux \u00e0 planter en automne<\/a><\/li><li><a href=https:\/\/www.expondo.be\/inspirations\/jardin-en-automne\/#6-un-potager-dans-le-jardin-en-automne->Un potager dans le jardin en automne&nbsp;?<\/a><\/li><li><a href=https:\/\/www.expondo.be\/inspirations\/jardin-en-automne\/#7-outils-essentiels-au-jardinage-dautomne>Outils essentiels au jardinage d&#8217;automne<\/a><\/li><li><a href=https:\/\/www.expondo.be\/inspirations\/jardin-en-automne\/#8-quelles-plantes-poussent-dans-le-jardin-en-automne-en-bref>Quelles plantes poussent dans le jardin en automne&nbsp;? En bref<\/a><\/li><\/ul><\/div><\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"0-comment-pr%C3%A9parer-mon-jardin-%C3%A0-lautomne-\">Comment pr\u00e9parer mon jardin \u00e0 l&#8217;automne&nbsp;?<\/h2>\n\n\n\n<p>Envie de passer du temps dans le jardin peu importe la saison&nbsp;? Alors, pr\u00e9parez-vous \u00e0 l&#8217;automne&nbsp;! <strong>Cette saison est particuli\u00e8rement propice \u00e0 la plantation de nombreuses plantes.<\/strong> Le sol est encore gorg\u00e9 de la chaleur estivale et offre aux nouvelles pousses des conditions optimales \u00e0 la pr\u00e9paration aux temp\u00e9ratures de l&#8217;hiver.<br><strong>La pluie arrose copieusement le jardin en automne<\/strong>, ce qui est tr\u00e8s appr\u00e9ci\u00e9 des plantes venant d&#8217;\u00eatre mises en terre. Au d\u00e9but du printemps, les v\u00e9g\u00e9taux plant\u00e9s en fin d&#8217;ann\u00e9e croissent avec vigueur, car ils n&#8217;ont pas besoin de d\u00e9penser de l&#8217;\u00e9nergie en cr\u00e9ant de nouvelles racines. C&#8217;est pourquoi ils sont plus vivaces l&#8217;\u00e9t\u00e9 que ceux plant\u00e9s apr\u00e8s les derni\u00e8res gel\u00e9es.<\/p>\n\n\n\n<p>Prendre soin de son jardin en automne ne signifie pas seulement se d\u00e9barrasser des feuilles mortes et prot\u00e9ger les plantes du gel. Pour beaucoup de plantes, c&#8217;est la saison de leur nouvelle vie, qui se d\u00e9veloppe dans les mois suivants pour devenir le plus bel ornement du jardin.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"1-les-v%C3%A9g%C3%A9taux-%C3%A0-planter-en-automne\">Les v\u00e9g\u00e9taux \u00e0 planter en automne<\/h2>\n\n\n\n<p>Peu importe si vous voulez arranger un jardin rustique ou un jardin tendance et moderne&nbsp;! Dans tous les cas, il vous faudra des plantes \u00e0 mettre en terre d\u00e8s le d\u00e9but de l&#8217;automne. Mais quelle sont-elles&nbsp;? <strong>Toutes sortes d&#8217;arbres et arbustes, de nombreuses plantes vivaces, des bulbes et m\u00eame certaines plantes \u00e0 graines&nbsp;!<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"2-arbres-et-arbustes\">Arbres et arbustes<\/h3>\n\n\n\n<p>Dans le verger, l&#8217;automne est la p\u00e9riode id\u00e9ale pour planter la plupart des arbres fruitiers (\u00e0 l&#8217;exception des p\u00eachers et abricotiers, trop sensibles au froid, ces plantes se plaisent mieux en d\u00e9but d&#8217;ann\u00e9e). Les pommiers, poiriers, cerisiers et autres arbres plant\u00e9s en octobre ou en novembre ont en revanche le temps de se r\u00e9g\u00e9n\u00e9rer avant l&#8217;<mdspan datatext=\"el1730120795425\" class=\"mdspan-comment\"><a href=\"https:\/\/www.expondo.be\/inspirations\/jardinage-en-hiver\/\" target=\"_blank\" rel=\"noreferrer noopener\">hiver dans le jardin<\/a><\/mdspan>. Au printemps, ils fleurissent et produisent alors vos fruits pr\u00e9f\u00e9r\u00e9s.<\/p>\n\n\n\n<p>Il en va de fa\u00e7on m\u00eame pour les arbustes \u00e0 baies. Si vous souhaitez cultiver vos propres groseilles, groseilles \u00e0 maquereau, framboises ou myrtilles, l&#8217;automne est la p\u00e9riode r\u00eav\u00e9e pour les mettre en terre.<\/p>\n\n\n\n<p>L&#8217;automne est non seulement la bonne p\u00e9riode pour trouver une place dans le jardin pour vos arbres fruitiers, mais aussi pour les plantes ornementales traditionnelles. Elles vous remercieront l&#8217;ann\u00e9e prochaine en cr\u00e9ant un paysage magnifique autour de votre maison. <strong>H\u00eatres, berb\u00e9ris, reine des pr\u00e9s, divers conif\u00e8res comme les ifs, les \u00e9pic\u00e9as, les gen\u00e9vriers, les pins et m\u00eame les reines du jardin, les roses<\/strong>&nbsp;: en automne, la plupart des arbres et arbustes ont beaucoup plus de chances de s&#8217;\u00e9tablir qu&#8217;au printemps.<\/p>\n\n\n\n<p>Les jardins d&#8217;automne offrent en outre des conditions propices \u00e0 la plantation de haies. Si vous souhaitez planter une haie de thuyas ou d&#8217;autres plantes conif\u00e8res, septembre et octobre sont les mois id\u00e9aux&nbsp;! Ce type de plantations a besoin de beaucoup d&#8217;eau pour d\u00e9velopper leurs racines. C&#8217;est pourquoi les pluies automnales sont plus que bienvenues. Si, malgr\u00e9 tout, il ne pleut pas pendant des semaines, pensez \u00e0 arroser vous-m\u00eame vos cl\u00f4tures de verdure&nbsp;!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"3-plantes-vivaces\">Plantes vivaces<\/h3>\n\n\n\n<p>La r\u00e8gle g\u00e9n\u00e9rale pour les plantes vivaces&nbsp;: <strong>les plantes \u00e0 floraison printani\u00e8re doivent \u00eatre mises en terre en automne et les plantes qui s&#8217;\u00e9panouissent de juillet \u00e0 octobre, au printemps<\/strong>. Dans tous les cas, les plantes vivaces se plaisent dans le jardin toute l&#8217;ann\u00e9e, except\u00e9 en hiver. C&#8217;est pourquoi il est important de les planter en automne&nbsp;: elles b\u00e9n\u00e9ficient des meilleures conditions de croissance et vous \u00e9vitez d&#8217;avoir \u00e0 les arroser constamment comme ce serait le cas en plein c\u0153ur de l&#8217;\u00e9t\u00e9. Quelles plantes vivaces doivent \u00eatre mises en terre en automne&nbsp;? Quelques exemples&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bergenia<\/li>\n\n\n\n<li>Phlox<\/li>\n\n\n\n<li>Sedum<\/li>\n\n\n\n<li>Forsythia<\/li>\n\n\n\n<li>Hell\u00e9bore noir<\/li>\n\n\n\n<li>Rhododendron<\/li>\n\n\n\n<li>Hortensia<\/li>\n\n\n\n<li>Delphinium<\/li>\n<\/ul>\n\n\n\n<p><strong inert=\"true\">Certaines plantes vivaces poss\u00e8dent des feuilles d\u00e9coratives et sont particuli\u00e8rement appr\u00e9ci\u00e9s.<\/strong> Parmi elles, on compte par exemple les arums, les hostas ou encore la La\u00eeche \u00e0 feuilles de plantain. Vous pouvez planter ces esp\u00e8ces toutes l&#8217;ann\u00e9e. Vous envisagez de planter un <mdspan datatext=\"el1729257689420\" class=\"mdspan-comment\"><a href=\"https:\/\/www.expondo.be\/inspirations\/comment-faire-un-jardin-en-rocaille\/\" target=\"_blank\" rel=\"noreferrer noopener\">jardin en rocaille<\/a><\/mdspan>&nbsp;? La plantation en automne vous permettra d&#8217;atteindre cet objectif&nbsp;!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"4-graines-de-fleurs\">Graines de fleurs<\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n        <div id=\"block_41fcc02f2ebf6676ea1270b828aeffe5\" class=\"wpmagus-block expondo-block expondo-block-photo-with-hotspots\">\n          <div\n            class=\"wpmagus-block__inner-container expondo-block__inner-container photo-with-hotspots-container\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.expondo.be\/inspirations\/wp-content\/uploads\/2022\/07\/10090175-4-1088x725.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.expondo.be\/inspirations\/wp-content\/uploads\/2022\/07\/10090175-4-1088x725.jpg 1088w, https:\/\/www.expondo.be\/inspirations\/wp-content\/uploads\/2022\/07\/10090175-4-300x200.jpg 300w, https:\/\/www.expondo.be\/inspirations\/wp-content\/uploads\/2022\/07\/10090175-4-768x512.jpg 768w, https:\/\/www.expondo.be\/inspirations\/wp-content\/uploads\/2022\/07\/10090175-4-1536x1024.jpg 1536w, https:\/\/www.expondo.be\/inspirations\/wp-content\/uploads\/2022\/07\/10090175-4.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>            <ul class=\"list list--hotspots\">\n                              <li class=\"item\" style=\"left: 40.00%; top: 27.00%;\">\n                  <button class=\"hotspot\"\n                    >+<\/button>\n                  <div class=\"description\" style=\"position:relative;z-index:10;padding:24px;\">\n                                          <a href=\"\/hillvert-brouette-de-jardin-caisse-basculante-550-kg-150-l-10090175\"\n                        style=\"position: absolute;width:100%;height:100%;\"><\/a>\n                      <img decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10090175_photo_1\">\n                      <strong class=\"title\"><a\n                          href=\"\/hillvert-brouette-de-jardin-caisse-basculante-550-kg-150-l-10090175\">\n                          Brouette de jardin &#8211; Caisse basculante &#8211; 550 kg &#8211; 150 l<\/a>\n                      <\/strong>\n                      <a style=\"text-decoration: underline;display:block;color:#000;font-size:1.4rem;font-weight:600;margin-top:84px;\"\n                        href=\"\/hillvert-brouette-de-jardin-caisse-basculante-550-kg-150-l-10090175\/\">Commandez maintenant<\/a>\n                                                                                  <span class=\"price\">        <ins>285.00&nbsp;\u20ac<\/ins>\n<\/span>\n                                      <\/div>\n                <\/li>\n                          <\/ul>\n                          <div class=\"description description--mob\"\n                style=\"display: none!important;position: relative; z-index: 10;transform: translateY(-50%);margin: 0 10%;padding: 2rem;border-radius: 8px;\">\n                                  <a href=\"\/hillvert-brouette-de-jardin-caisse-basculante-550-kg-150-l-10090175\"\n                    style=\"position: absolute;width:100%;height:100%;\"><\/a>\n                  <img decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10090175_photo_1\">\n                  <strong class=\"title\"><a\n                      href=\"\/hillvert-brouette-de-jardin-caisse-basculante-550-kg-150-l-10090175\">Brouette de jardin &#8211; Caisse basculante &#8211; 550 kg &#8211; 150 l<\/a><\/strong>\n                  <a style=\"text-decoration: underline;display:block;color:#000;font-size:1.4rem;font-weight:600;margin-top:84px;\"\n                    href=\"\/hillvert-brouette-de-jardin-caisse-basculante-550-kg-150-l-10090175\">Commandez maintenant<\/a>\n                                                                  <span class=\"price\">        <ins>285.00&nbsp;\u20ac<\/ins>\n<\/span>\n                              <\/div>\n                      <\/div>\n        <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p>Semis riment avec printemps. Mais saviez-vous que certaines esp\u00e8ces de plantes peuvent \u00eatre sem\u00e9es en automne&nbsp;? <strong>Les soucis, delphiniums, myosotis, bleuets et violettes poussent bien lorsque vous les plantez entre septembre et octobre&nbsp;!<\/strong><\/p>\n\n\n\n<p>Certaines graines appr\u00e9cient le gel et passent l&#8217;hiver recouvertes de neige, tandis que d&#8217;autres ne germent qu&#8217;au printemps. Dans les deux cas, vous pouvez toutefois vous attendre \u00e0 une croissance pr\u00e9coce de ces plantes et donc \u00e0 une floraison plus rapide. N\u00e9anmoins, en cas d&#8217;hiver rigoureux, il est possible que les semis g\u00e8lent. Pour \u00e9viter cela, <strong>recouvrez vos plates-bandes sem\u00e9es de brindilles d&#8217;\u00e9pic\u00e9a ou d&#8217;agrotextile.<\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"5-bulbes-de-fleurs\">Bulbes de fleurs<\/h3>\n\n\n\n<p>Septembre, octobre ou encore novembre, vous disposez de toute la saison automnale pour mettre en terre des bulbes qui donneront naissance \u00e0 de magnifiques fleurs au printemps&nbsp;! Enterrez les bulbes \u00e0 environ 15&nbsp;cm de profondeur. Quelles esp\u00e8ces peuvent \u00eatre plant\u00e9es en automne&nbsp;?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Crocus<\/li>\n\n\n\n<li>Ail \u00e0 t\u00eate ronde<\/li>\n\n\n\n<li>Narcisse<\/li>\n\n\n\n<li>Perce-neige<\/li>\n\n\n\n<li>Hell\u00e9bore d&#8217;hiver<\/li>\n\n\n\n<li>Tulipe<\/li>\n\n\n\n<li>Jacinthe<\/li>\n\n\n\n<li>Lys<\/li>\n\n\n\n<li>\u00c9toile de Perse<\/li>\n\n\n\n<li>Astrance<\/li>\n\n\n\n<li>An\u00e9mone<\/li>\n\n\n\n<li>Niv\u00e9ole de printemps<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"6-un-potager-dans-le-jardin-en-automne-\">Un potager dans le jardin en automne&nbsp;?<\/h2>\n\n\n\n<p>Le travail avec les plantes d&#8217;ornement dans le jardin en automne est une bonne id\u00e9e, mais avez-vous pens\u00e9 \u00e0 cultiver des l\u00e9gumes&nbsp;? \u00c0 la fin de l&#8217;\u00e9t\u00e9, il est d\u00e9j\u00e0 possible de semer des l\u00e9gumes insensibles au froid comme les radis, les salades ou les navets. Les oignons, l&#8217;ail et les carottes se plaisent aussi dans le climat automnal&nbsp;! Pensez toutefois \u00e0 semer les graines un peu plus dens\u00e9ment en cette saison qu&#8217;en d\u00e9but d&#8217;ann\u00e9e, car tous les plans ne survivront pas l&#8217;hiver.<\/p>\n\n\n\n<p>Dans les potagers d&#8217;automne, il y a une autre t\u00e2che \u00e0 accomplir&nbsp;: <strong>semer une culture interm\u00e9diaire qui enrichira le sol avant la prochaine saison de l\u00e9gumes<\/strong>. Vous avez le choix entre une culture interm\u00e9diaire \u00e0 croissance rapide, que vous enfouissez dans le sol apr\u00e8s quelques semaines pour lui apporter des nutriments, et une culture interm\u00e9diaire d&#8217;hiver, que vous n&#8217;enfouissez qu&#8217;au printemps.<\/p>\n\n\n              <div id=\"expondo-products-block_dad114fc1098ed3e16f5701a57ea3241\" class=\"expondo-block expondo-block--products\">\n          <div class=\"expondo-block__inner-container\">\n            <ul class=\"list list--products\">\n                              <li class=\"item\">\n                  <a href=\"\/hillvert-epandeur-engrais-14-l-largeur-d-epandage-de-1-a-3-m-10090135\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10090135_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/hillvert-epandeur-engrais-14-l-largeur-d-epandage-de-1-a-3-m-10090135\">\n                        \u00c9pandeur engrais &#8211; 15 l &#8211; Largeur d\u2019\u00e9pandage de 1 \u00e0 3 m                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                              <ins>68.00&nbsp;\u20ac<\/ins>\n                    <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/hillvert-siege-de-jardinage-avec-compartiment-de-rangement-80-kg-10090174\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10090174_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/hillvert-siege-de-jardinage-avec-compartiment-de-rangement-80-kg-10090174\">\n                        Si\u00e8ge de jardinage &#8211; Avec compartiment de rangement &#8211; 80 kg                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/hillvert-composteur-de-jardin-1-000-l-10090213\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10090213_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/hillvert-composteur-de-jardin-1-000-l-10090213\">\n                        Composteur de jardin &#8211; 1\u00a0000 l                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                                          <\/span>\n                                  <\/li>\n                              <li class=\"item\">\n                  <a href=\"\/msw-enrouleur-de-cable-automatique-20-m-1-5-m-10060680\">\n                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets.expondo.com\/asset\/product_photos\/10060680_photo_1\" width=\"600\" height=\"600\" alt=\"\" class=\"image\" \/>\n                  <\/a>\n                  <strong class=\"title\">\n                    <a href=\"\/msw-enrouleur-de-cable-automatique-20-m-1-5-m-10060680\">\n                        Enrouleur de c\u00e2ble &#8211; automatique &#8211; 20 m + 1,5 m                    <\/a>\n                  <\/strong>\n\n                                      <span class=\"price\">\n                              <ins>80.00&nbsp;\u20ac<\/ins>\n                    <\/span>\n                                  <\/li>\n                          <\/ul>\n          <\/div>\n        <\/div>\n        \n\n\n<h2 class=\"wp-block-heading\" id=\"7-outils-essentiels-au-jardinage-dautomne\">Outils essentiels au jardinage d&#8217;automne<\/h2>\n\n\n\n<p>Une fois que vous avez d\u00e9cid\u00e9 ce que vous souhaitez planter dans votre jardin en automne, il est temps de vous armer de vos <mdspan datatext=\"el1729257607891\" class=\"mdspan-comment\"><a href=\"https:\/\/www.expondo.be\/outil-de-jardinage\/\" target=\"_blank\" rel=\"noreferrer noopener\">outils de jardinage<\/a><\/mdspan>\u00a0! Pour b\u00eacher et a\u00e9rer le sol et d\u00e9sherber, vous n&#8217;avez besoin que d&#8217;outils rudimentaires, <strong>particuli\u00e8rement d&#8217;une pelle solide, d&#8217;un r\u00e2teau et d&#8217;une pioche<\/strong>. Cela vous permettra de retirer plus facilement les rhizomes et autres mauvaises herbes de la terre ameublie. Un plantoir \u00e0 bulbes pourra \u00e9galement vous \u00eatre utile. Avec lui, vous d\u00e9coupez sans peine des trous dans la pelouse. Ensuite, vous recouvrez les bulbes avec le morceau de pelouse d\u00e9coup\u00e9, qui se r\u00e9g\u00e9n\u00e8re rapidement.<\/p>\n\n\n\n<p>Toutes les nouvelles plantes dans votre jardin d&#8217;automne ont besoin d&#8217;\u00eatre arros\u00e9es r\u00e9guli\u00e8rement. C&#8217;est pourquoi il est essentiel de <mdspan datatext=\"el1729257622245\" class=\"mdspan-comment\"><a href=\"https:\/\/www.expondo.be\/inspirations\/comment-planifier-lirrigation-de-son-jardin\/\" target=\"_blank\" rel=\"noreferrer noopener\">planifier l&#8217;irrigation de votre jardin<\/a><\/mdspan> et d&#8217;installer un syst\u00e8me automatique qui prend soin de vos plants en cas d&#8217;automne sec.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"8-quelles-plantes-poussent-dans-le-jardin-en-automne-en-bref\">Quelles plantes poussent dans le jardin en automne&nbsp;? En bref<\/h2>\n\n\n\n<p>Les jardins d&#8217;automne sont magnifiques et pr\u00eatent au r\u00eave. Pour les paysagistes en herbe, le travail ne s&#8217;arr\u00eate pas \u00e0 la fin de l&#8217;\u00e9t\u00e9. Si vous effectuez ces t\u00e2ches avant l&#8217;hiver, vous admirerez de beaux r\u00e9sultats au d\u00e9but du printemps. La plantation d&#8217;arbres, d&#8217;arbustes, de plantes vivaces, de bulbes et de graines est non seulement possible, mais aussi, dans de nombreux cas, souhaitable \u00e0 cette p\u00e9riode de l&#8217;ann\u00e9e. Ne manquez donc pas la meilleure p\u00e9riode pour que les plantes s&#8217;enracinent dans le sol. Profitez de cette p\u00e9riode pour am\u00e9nager votre jardin et profiter l&#8217;ann\u00e9e suivante de magnifiques floraisons&nbsp;!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;automne marque la fin des beaux jours. C&#8217;est n\u00e9anmoins aussi la saison id\u00e9ale pour r\u00e9aliser certains&hellip;<\/p>\n","protected":false},"author":21,"featured_media":43588,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_sb_is_suggestion_mode":false,"_sb_show_suggestion_boards":false,"_sb_show_comment_boards":false,"_sb_suggestion_history":"","_sb_update_block_changes":"","ub_ctt_via":"","rank_math_lock_modified_date":false,"_strive_post_notes":"577\r\nLinks\r\n1. 578\r\nhttps:\/\/www.expondo.co.uk\/inspirations\/garden-work-in-winter\/\r\n\r\nhttps:\/\/www.expondo.de\/inspirationen\/gartenarbeiten-im-winter\/\r\n\r\nhttps:\/\/www.expondo.fr\/inspirations\/jardinage-en-hiver\/\r\n\r\nhttps:\/\/www.expondo.it\/ispirazioni\/giardinaggio-in-inverno\/\r\n\r\nhttps:\/\/www.expondo.se\/inspiration\/tradgard-pa-vintern\/\r\n\r\nhttps:\/\/www.expondo.ie\/inspirations\/garden-work-in-winter\/\r\n\r\nhttps:\/\/www.expondo.at\/inspirationen\/gartenarbeiten-im-winter\/\r\n\r\nhttps:\/\/www.expondo.be\/inspirations\/jardinage-en-hiver\/\r\n\r\n\r\n\r\n2. 350 - \r\nNO IT and SE yet, leave a comment ID 350\r\n\r\nhttps:\/\/www.expondo.co.uk\/inspirations\/how-to-build-a-rock-garden\/\r\n\r\nhttps:\/\/www.expondo.de\/inspirationen\/steingarten-richtig-anlegen-anleitung-tipps\/\r\nhttps:\/\/www.expondo.fr\/inspirations\/comment-faire-un-jardin-en-rocaille\/\r\n\r\n\r\nhttps:\/\/www.expondo.ie\/inspirations\/how-to-build-a-rock-garden\/\r\n\r\nhttps:\/\/www.expondo.at\/inspirationen\/steingarten-richtig-anlegen-anleitung-tipps\/\r\n\r\nhttps:\/\/www.expondo.be\/inspirations\/comment-faire-un-jardin-en-rocaille\/\r\n\r\nhttps:\/\/www.expondo.hu\/inspiraciok\/hogyan-epitsunk-sziklakertet\/\r\n\r\n\r\n3. https:\/\/www.expondo.de\/gartengeraete\/\r\nhttps:\/\/www.expondo.co.uk\/garden-tools\/\r\nhttps:\/\/www.expondo.fr\/outil-de-jardinage\/\r\nhttps:\/\/www.expondo.it\/attrezzi-da-giardino\/\r\nhttps:\/\/www.expondo.se\/traedgaardsredskap\/\r\nhttps:\/\/www.expondo.hu\/kerti-eszkoezoek-1d5f0408\/\r\n\r\n\r\n4. 294 - \r\n\r\nhttps:\/\/www.expondo.pl\/inspiracje\/nawadnianie-ogrodu-jak-zaplanowac-system-podlewania\/\r\n\r\nhttps:\/\/www.expondo.co.uk\/inspirations\/how-to-plan-a-garden-irrigation-system-a-guide\/\r\n\r\nhttps:\/\/www.expondo.de\/inspirationen\/so-plant-man-ein-gartenbewasserungssystem\/\r\n\r\nhttps:\/\/www.expondo.fr\/inspirations\/comment-planifier-lirrigation-de-son-jardin\/\r\n\r\n\r\nhttps:\/\/www.expondo.ie\/inspirations\/how-to-plan-a-garden-irrigation-system-a-guide\/\r\n\r\nhttps:\/\/www.expondo.at\/inspirationen\/so-plant-man-ein-gartenbewasserungssystem\/\r\n\r\nhttps:\/\/www.expondo.be\/inspirations\/comment-planifier-lirrigation-de-son-jardin\/\r\n\r\nhttps:\/\/www.expondo.hu\/inspiraciok\/igy-tervezunk-kerti-ontozorendszert\/","footnotes":""},"categories":[3098],"tags":[],"promotion":[],"class_list":["post-88998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-maison-et-jardin-fr-be"],"acf":[],"featured_image_src":"https:\/\/www.expondo.be\/inspirations\/wp-content\/uploads\/2022\/07\/autumn-in-the-garden.jpg","author_info":{"display_name":"Aleksandra Mojka","author_link":"https:\/\/www.expondo.be\/inspirations\/author\/aleksandra-mojka\/"},"reading_time":"6","author_thumbnail":"https:\/\/secure.gravatar.com\/avatar\/c6bea5b84cf5de4bc1f64d8190012798?s=96&d=mm&r=g","excerpt_full":"\n<p><strong>L'automne marque la fin des beaux jours. C'est n\u00e9anmoins aussi la saison id\u00e9ale pour r\u00e9aliser certains travaux de jardinage essentiels. C'est le moment de planter des arbres, des arbustes ou encore des bulbes. Comment pr\u00e9parer son jardin en automne pour qu'il fleurisse, d\u00e9veloppe ses couleurs et que les arbres soient en pleine sant\u00e9 au printemps&nbsp;?<\/strong><\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"0-comment-pr%C3%A9parer-mon-jardin-%C3%A0-lautomne-\">Comment pr\u00e9parer mon jardin \u00e0 l'automne&nbsp;?<\/h2>\n\n\n\n<p>Envie de passer du temps dans le jardin peu importe la saison&nbsp;? Alors, pr\u00e9parez-vous \u00e0 l'automne&nbsp;! <strong>Cette saison est particuli\u00e8rement propice \u00e0 la plantation de nombreuses plantes.<\/strong> Le sol est encore gorg\u00e9 de la chaleur estivale et offre aux nouvelles pousses des conditions optimales \u00e0 la pr\u00e9paration aux temp\u00e9ratures de l'hiver.<br><strong>La pluie arrose copieusement le jardin en automne<\/strong>, ce qui est tr\u00e8s appr\u00e9ci\u00e9 des plantes venant d'\u00eatre mises en terre. Au d\u00e9but du printemps, les v\u00e9g\u00e9taux plant\u00e9s en fin d'ann\u00e9e croissent avec vigueur, car ils n'ont pas besoin de d\u00e9penser de l'\u00e9nergie en cr\u00e9ant de nouvelles racines. C'est pourquoi ils sont plus vivaces l'\u00e9t\u00e9 que ceux plant\u00e9s apr\u00e8s les derni\u00e8res gel\u00e9es.<\/p>\n\n\n\n<p>Prendre soin de son jardin en automne ne signifie pas seulement se d\u00e9barrasser des feuilles mortes et prot\u00e9ger les plantes du gel. Pour beaucoup de plantes, c'est la saison de leur nouvelle vie, qui se d\u00e9veloppe dans les mois suivants pour devenir le plus bel ornement du jardin.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"1-les-v%C3%A9g%C3%A9taux-%C3%A0-planter-en-automne\">Les v\u00e9g\u00e9taux \u00e0 planter en automne<\/h2>\n\n\n\n<p>Peu importe si vous voulez arranger un jardin rustique ou un jardin tendance et moderne&nbsp;! Dans tous les cas, il vous faudra des plantes \u00e0 mettre en terre d\u00e8s le d\u00e9but de l'automne. Mais quelle sont-elles&nbsp;? <strong>Toutes sortes d'arbres et arbustes, de nombreuses plantes vivaces, des bulbes et m\u00eame certaines plantes \u00e0 graines&nbsp;!<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"2-arbres-et-arbustes\">Arbres et arbustes<\/h3>\n\n\n\n<p>Dans le verger, l'automne est la p\u00e9riode id\u00e9ale pour planter la plupart des arbres fruitiers (\u00e0 l'exception des p\u00eachers et abricotiers, trop sensibles au froid, ces plantes se plaisent mieux en d\u00e9but d'ann\u00e9e). Les pommiers, poiriers, cerisiers et autres arbres plant\u00e9s en octobre ou en novembre ont en revanche le temps de se r\u00e9g\u00e9n\u00e9rer avant l'<mdspan datatext=\"el1730120795425\" class=\"mdspan-comment\"><a href=\"https:\/\/www.expondo.be\/inspirations\/jardinage-en-hiver\/\" target=\"_blank\" rel=\"noreferrer noopener\">hiver dans le jardin<\/a><\/mdspan>. Au printemps, ils fleurissent et produisent alors vos fruits pr\u00e9f\u00e9r\u00e9s.<\/p>\n\n\n\n<p>Il en va de fa\u00e7on m\u00eame pour les arbustes \u00e0 baies. Si vous souhaitez cultiver vos propres groseilles, groseilles \u00e0 maquereau, framboises ou myrtilles, l'automne est la p\u00e9riode r\u00eav\u00e9e pour les mettre en terre.<\/p>\n\n\n\n<p>L'automne est non seulement la bonne p\u00e9riode pour trouver une place dans le jardin pour vos arbres fruitiers, mais aussi pour les plantes ornementales traditionnelles. Elles vous remercieront l'ann\u00e9e prochaine en cr\u00e9ant un paysage magnifique autour de votre maison. <strong>H\u00eatres, berb\u00e9ris, reine des pr\u00e9s, divers conif\u00e8res comme les ifs, les \u00e9pic\u00e9as, les gen\u00e9vriers, les pins et m\u00eame les reines du jardin, les roses<\/strong>&nbsp;: en automne, la plupart des arbres et arbustes ont beaucoup plus de chances de s'\u00e9tablir qu'au printemps.<\/p>\n\n\n\n<p>Les jardins d'automne offrent en outre des conditions propices \u00e0 la plantation de haies. Si vous souhaitez planter une haie de thuyas ou d'autres plantes conif\u00e8res, septembre et octobre sont les mois id\u00e9aux&nbsp;! Ce type de plantations a besoin de beaucoup d'eau pour d\u00e9velopper leurs racines. C'est pourquoi les pluies automnales sont plus que bienvenues. Si, malgr\u00e9 tout, il ne pleut pas pendant des semaines, pensez \u00e0 arroser vous-m\u00eame vos cl\u00f4tures de verdure&nbsp;!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"3-plantes-vivaces\">Plantes vivaces<\/h3>\n\n\n\n<p>La r\u00e8gle g\u00e9n\u00e9rale pour les plantes vivaces&nbsp;: <strong>les plantes \u00e0 floraison printani\u00e8re doivent \u00eatre mises en terre en automne et les plantes qui s'\u00e9panouissent de juillet \u00e0 octobre, au printemps<\/strong>. Dans tous les cas, les plantes vivaces se plaisent dans le jardin toute l'ann\u00e9e, except\u00e9 en hiver. C'est pourquoi il est important de les planter en automne&nbsp;: elles b\u00e9n\u00e9ficient des meilleures conditions de croissance et vous \u00e9vitez d'avoir \u00e0 les arroser constamment comme ce serait le cas en plein c\u0153ur de l'\u00e9t\u00e9. Quelles plantes vivaces doivent \u00eatre mises en terre en automne&nbsp;? Quelques exemples&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n\n\n\n\n\n\n\n\n\n\n\n\n\n<\/ul>\n\n\n\n<p><strong inert=\"true\">Certaines plantes vivaces poss\u00e8dent des feuilles d\u00e9coratives et sont particuli\u00e8rement appr\u00e9ci\u00e9s.<\/strong> Parmi elles, on compte par exemple les arums, les hostas ou encore la La\u00eeche \u00e0 feuilles de plantain. Vous pouvez planter ces esp\u00e8ces toutes l'ann\u00e9e. Vous envisagez de planter un <mdspan datatext=\"el1729257689420\" class=\"mdspan-comment\"><a href=\"https:\/\/www.expondo.be\/inspirations\/comment-faire-un-jardin-en-rocaille\/\" target=\"_blank\" rel=\"noreferrer noopener\">jardin en rocaille<\/a><\/mdspan>&nbsp;? La plantation en automne vous permettra d'atteindre cet objectif&nbsp;!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"4-graines-de-fleurs\">Graines de fleurs<\/h3>\n\n\n\n<div class=\"wp-block-columns\">\n\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"5-bulbes-de-fleurs\">Bulbes de fleurs<\/h3>\n\n\n\n<p>Septembre, octobre ou encore novembre, vous disposez de toute la saison automnale pour mettre en terre des bulbes qui donneront naissance \u00e0 de magnifiques fleurs au printemps&nbsp;! Enterrez les bulbes \u00e0 environ 15&nbsp;cm de profondeur. Quelles esp\u00e8ces peuvent \u00eatre plant\u00e9es en automne&nbsp;?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"6-un-potager-dans-le-jardin-en-automne-\">Un potager dans le jardin en automne&nbsp;?<\/h2>\n\n\n\n<p>Le travail avec les plantes d'ornement dans le jardin en automne est une bonne id\u00e9e, mais avez-vous pens\u00e9 \u00e0 cultiver des l\u00e9gumes&nbsp;? \u00c0 la fin de l'\u00e9t\u00e9, il est d\u00e9j\u00e0 possible de semer des l\u00e9gumes insensibles au froid comme les radis, les salades ou les navets. Les oignons, l'ail et les carottes se plaisent aussi dans le climat automnal&nbsp;! Pensez toutefois \u00e0 semer les graines un peu plus dens\u00e9ment en cette saison qu'en d\u00e9but d'ann\u00e9e, car tous les plans ne survivront pas l'hiver.<\/p>\n\n\n\n<p>Dans les potagers d'automne, il y a une autre t\u00e2che \u00e0 accomplir&nbsp;: <strong>semer une culture interm\u00e9diaire qui enrichira le sol avant la prochaine saison de l\u00e9gumes<\/strong>. Vous avez le choix entre une culture interm\u00e9diaire \u00e0 croissance rapide, que vous enfouissez dans le sol apr\u00e8s quelques semaines pour lui apporter des nutriments, et une culture interm\u00e9diaire d'hiver, que vous n'enfouissez qu'au printemps.<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"7-outils-essentiels-au-jardinage-dautomne\">Outils essentiels au jardinage d'automne<\/h2>\n\n\n\n<p>Une fois que vous avez d\u00e9cid\u00e9 ce que vous souhaitez planter dans votre jardin en automne, il est temps de vous armer de vos <mdspan datatext=\"el1729257607891\" class=\"mdspan-comment\"><a href=\"https:\/\/www.expondo.be\/outil-de-jardinage\/\" target=\"_blank\" rel=\"noreferrer noopener\">outils de jardinage<\/a><\/mdspan>\u00a0! Pour b\u00eacher et a\u00e9rer le sol et d\u00e9sherber, vous n'avez besoin que d'outils rudimentaires, <strong>particuli\u00e8rement d'une pelle solide, d'un r\u00e2teau et d'une pioche<\/strong>. Cela vous permettra de retirer plus facilement les rhizomes et autres mauvaises herbes de la terre ameublie. Un plantoir \u00e0 bulbes pourra \u00e9galement vous \u00eatre utile. Avec lui, vous d\u00e9coupez sans peine des trous dans la pelouse. Ensuite, vous recouvrez les bulbes avec le morceau de pelouse d\u00e9coup\u00e9, qui se r\u00e9g\u00e9n\u00e8re rapidement.<\/p>\n\n\n\n<p>Toutes les nouvelles plantes dans votre jardin d'automne ont besoin d'\u00eatre arros\u00e9es r\u00e9guli\u00e8rement. C'est pourquoi il est essentiel de <mdspan datatext=\"el1729257622245\" class=\"mdspan-comment\"><a href=\"https:\/\/www.expondo.be\/inspirations\/comment-planifier-lirrigation-de-son-jardin\/\" target=\"_blank\" rel=\"noreferrer noopener\">planifier l'irrigation de votre jardin<\/a><\/mdspan> et d'installer un syst\u00e8me automatique qui prend soin de vos plants en cas d'automne sec.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"8-quelles-plantes-poussent-dans-le-jardin-en-automne-en-bref\">Quelles plantes poussent dans le jardin en automne&nbsp;? En bref<\/h2>\n\n\n\n<p>Les jardins d'automne sont magnifiques et pr\u00eatent au r\u00eave. Pour les paysagistes en herbe, le travail ne s'arr\u00eate pas \u00e0 la fin de l'\u00e9t\u00e9. Si vous effectuez ces t\u00e2ches avant l'hiver, vous admirerez de beaux r\u00e9sultats au d\u00e9but du printemps. La plantation d'arbres, d'arbustes, de plantes vivaces, de bulbes et de graines est non seulement possible, mais aussi, dans de nombreux cas, souhaitable \u00e0 cette p\u00e9riode de l'ann\u00e9e. Ne manquez donc pas la meilleure p\u00e9riode pour que les plantes s'enracinent dans le sol. Profitez de cette p\u00e9riode pour am\u00e9nager votre jardin et profiter l'ann\u00e9e suivante de magnifiques floraisons&nbsp;!<\/p>\n","_links":{"self":[{"href":"https:\/\/www.expondo.be\/inspirations\/wp-json\/wp\/v2\/posts\/88998"}],"collection":[{"href":"https:\/\/www.expondo.be\/inspirations\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expondo.be\/inspirations\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expondo.be\/inspirations\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expondo.be\/inspirations\/wp-json\/wp\/v2\/comments?post=88998"}],"version-history":[{"count":1,"href":"https:\/\/www.expondo.be\/inspirations\/wp-json\/wp\/v2\/posts\/88998\/revisions"}],"predecessor-version":[{"id":89000,"href":"https:\/\/www.expondo.be\/inspirations\/wp-json\/wp\/v2\/posts\/88998\/revisions\/89000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expondo.be\/inspirations\/wp-json\/wp\/v2\/media\/43588"}],"wp:attachment":[{"href":"https:\/\/www.expondo.be\/inspirations\/wp-json\/wp\/v2\/media?parent=88998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expondo.be\/inspirations\/wp-json\/wp\/v2\/categories?post=88998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expondo.be\/inspirations\/wp-json\/wp\/v2\/tags?post=88998"},{"taxonomy":"promotion","embeddable":true,"href":"https:\/\/www.expondo.be\/inspirations\/wp-json\/wp\/v2\/promotion?post=88998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}